{"id":1,"name":"fireflythemes","url":"","description":"","link":"https:\/\/demo.fireflythemes.com\/jetblack-music-free\/author\/fireflythemes\/","slug":"fireflythemes","avatar_urls":{"24":"https:\/\/demo.fireflythemes.com\/jetblack-music-free\/wp-content\/litespeed\/avatar\/54\/a2bd319bd7ad7d14f499b10fb5652605.jpg?ver=1778024977","48":"https:\/\/demo.fireflythemes.com\/jetblack-music-free\/wp-content\/litespeed\/avatar\/54\/e592192daa115cca23dc8248b76ba832.jpg?ver=1778024977","96":"https:\/\/demo.fireflythemes.com\/jetblack-music-free\/wp-content\/litespeed\/avatar\/54\/599523d857b8762615be67db26caa8ad.jpg?ver=1778024977"},"meta":[],"is_super_admin":true,"woocommerce_meta":{"variable_product_tour_shown":"","activity_panel_inbox_last_read":"","activity_panel_reviews_last_read":"","categories_report_columns":"","coupons_report_columns":"","customers_report_columns":"","orders_report_columns":"","products_report_columns":"","revenue_report_columns":"","taxes_report_columns":"","variations_report_columns":"","dashboard_sections":"","dashboard_chart_type":"","dashboard_chart_interval":"","dashboard_leaderboard_rows":"","order_attribution_install_banner_dismissed":"","scheduled_updates_promotion_notice_dismissed":"","homepage_layout":"","homepage_stats":"","task_list_tracked_started_tasks":"","android_app_banner_dismissed":"","launch_your_store_tour_hidden":"","coming_soon_banner_dismissed":""},"_links":{"self":[{"href":"https:\/\/demo.fireflythemes.com\/jetblack-music-free\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.fireflythemes.com\/jetblack-music-free\/wp-json\/wp\/v2\/users"}]}}